{"id":44,"date":"2023-10-03T12:48:01","date_gmt":"2023-10-03T10:48:01","guid":{"rendered":"https:\/\/fitgymaltea.es\/?page_id=44"},"modified":"2024-02-14T14:13:10","modified_gmt":"2024-02-14T13:13:10","slug":"gimansio","status":"publish","type":"page","link":"https:\/\/entornopruebas123.es\/en\/gimansio\/","title":{"rendered":"GYM"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"44\" class=\"elementor elementor-44\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f6f7531 e-flex e-con-boxed e-con e-parent\" data-id=\"f6f7531\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3014117 animated-fast elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"3014117\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FITGYM ALTEA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-576ce604 animated-fast elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"576ce604\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">GYM<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b335b49 e-flex e-con-boxed e-con e-parent\" data-id=\"b335b49\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-07c8ed3 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"07c8ed3\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6238c7 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"a6238c7\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">galer\u00eda<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85d57cc elementor-arrows-position-outside elementor-pagination-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"85d57cc\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;3&quot;,&quot;autoplay_speed&quot;:2000,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/entornopruebas123.es\/wp-content\/uploads\/2023\/11\/19-1-2048x1536.jpg\" alt=\"19\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/entornopruebas123.es\/wp-content\/uploads\/2023\/11\/21-1-2048x1536.jpg\" alt=\"21\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/entornopruebas123.es\/wp-content\/uploads\/2023\/11\/22-2048x1536.jpg\" alt=\"22\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/entornopruebas123.es\/wp-content\/uploads\/2023\/11\/24-1-2048x1536.jpg\" alt=\"24\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/entornopruebas123.es\/wp-content\/uploads\/2023\/11\/12-2048x1365.jpg\" alt=\"12\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/entornopruebas123.es\/wp-content\/uploads\/2023\/11\/20-1-2048x1536.jpg\" alt=\"20\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/entornopruebas123.es\/wp-content\/uploads\/2023\/11\/23-2048x1536.jpg\" alt=\"23\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/entornopruebas123.es\/wp-content\/uploads\/2023\/11\/6-1-2048x1365.jpg\" alt=\"6\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/entornopruebas123.es\/wp-content\/uploads\/2023\/11\/14-1-2048x1536.jpg\" alt=\"14\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/entornopruebas123.es\/wp-content\/uploads\/2023\/11\/16-2048x1536.jpg\" alt=\"16\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/entornopruebas123.es\/wp-content\/uploads\/2023\/11\/17-2048x1536.jpg\" alt=\"17\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/entornopruebas123.es\/wp-content\/uploads\/2023\/11\/9-2048x1365.jpg\" alt=\"9\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1c2670 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a1c2670\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6807bf1f e-con-full e-flex e-con e-parent\" data-id=\"6807bf1f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-b51e2c5 e-con-full e-flex e-con e-child\" data-id=\"b51e2c5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f8e256a animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"f8e256a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">OURS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2eb65d88 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"2eb65d88\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ACTIVITIES<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1b798471 e-con-full e-flex e-con e-child\" data-id=\"1b798471\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5cf3154 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5cf3154\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-736ca44 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"736ca44\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/fitgymaltea.es\/?page_id=81\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">VER M\u00c1S<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f46aab5 e-flex e-con-boxed e-con e-parent\" data-id=\"f46aab5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f494ba6 e-con-full e-flex e-con e-child\" data-id=\"f494ba6\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-931c6b2 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"931c6b2\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ENTRENA CON LAS MEJORES<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77b6462 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"77b6462\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FACILITIES<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a554da8 elementor-widget elementor-widget-text-editor\" data-id=\"a554da8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El gimnasio tiene varios equipos y \u00e1reas para hacer ejercicios, como musculaci\u00f3n, cardio, yoga, zumba y m\u00e1s. Tambi\u00e9n ofrece servicios como vestidores, ba\u00f1os, cafeter\u00edas y peque\u00f1a tienda de suplementos. Es perfecto para cualquier nivel deportivo y cuenta con supervisi\u00f3n profesional.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-542d710 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"542d710\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/fitgymaltea.es\/?page_id=79\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SABER M\u00c1S<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f22f5d elementor-widget elementor-widget-image\" data-id=\"1f22f5d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/entornopruebas123.es\/wp-content\/uploads\/2023\/11\/14-1024x768.jpg\" class=\"attachment-large size-large wp-image-593\" alt=\"\" srcset=\"https:\/\/entornopruebas123.es\/wp-content\/uploads\/2023\/11\/14-1024x768.jpg 1024w, https:\/\/entornopruebas123.es\/wp-content\/uploads\/2023\/11\/14-300x225.jpg 300w, https:\/\/entornopruebas123.es\/wp-content\/uploads\/2023\/11\/14-768x576.jpg 768w, https:\/\/entornopruebas123.es\/wp-content\/uploads\/2023\/11\/14-1536x1152.jpg 1536w, https:\/\/entornopruebas123.es\/wp-content\/uploads\/2023\/11\/14-2048x1536.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ec706fe e-flex e-con-boxed e-con e-parent\" data-id=\"ec706fe\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-510c82b elementor-widget__width-initial elementor-widget elementor-widget-video\" data-id=\"510c82b\" data-element_type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"http:\/\/fitgymaltea.es\/wp-content\/uploads\/2024\/01\/video-1.mp4\" controls=\"\" preload=\"metadata\" controlslist=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>FITGYM ALTEA GIMNASIO galer\u00eda NUESTRAS ACTIVIDADES VER M\u00c1S ENTRENA CON LAS MEJORES INSTALACIONES El gimnasio tiene varios equipos y \u00e1reas para hacer ejercicios, como musculaci\u00f3n, cardio, yoga, zumba y m\u00e1s. Tambi\u00e9n ofrece servicios como vestidores, ba\u00f1os, cafeter\u00edas y peque\u00f1a tienda de suplementos. Es perfecto para cualquier nivel deportivo y cuenta con supervisi\u00f3n profesional. SABER M\u00c1S [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"FITGYM ALTEA GIMNASIO galer\u00eda NUESTRAS ACTIVIDADES VER M\u00c1S ENTRENA CON LAS MEJORES INSTALACIONES El gimnasio tiene varios equipos y \u00e1reas para hacer ejercicios, como musculaci\u00f3n, cardio, yoga, zumba y m\u00e1s. Tambi\u00e9n ofrece servicios como vestidores, ba\u00f1os, cafeter\u00edas y peque\u00f1a tienda de suplementos. Es perfecto para cualquier nivel deportivo y cuenta con supervisi\u00f3n profesional. SABER M\u00c1S\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/entornopruebas123.es\/en\/gimansio\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_GB\" \/>\n\t\t<meta property=\"og:site_name\" content=\"fitgymaltea.es -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"GIMNASIO - fitgymaltea.es\" \/>\n\t\t<meta property=\"og:description\" content=\"FITGYM ALTEA GIMNASIO galer\u00eda NUESTRAS ACTIVIDADES VER M\u00c1S ENTRENA CON LAS MEJORES INSTALACIONES El gimnasio tiene varios equipos y \u00e1reas para hacer ejercicios, como musculaci\u00f3n, cardio, yoga, zumba y m\u00e1s. Tambi\u00e9n ofrece servicios como vestidores, ba\u00f1os, cafeter\u00edas y peque\u00f1a tienda de suplementos. Es perfecto para cualquier nivel deportivo y cuenta con supervisi\u00f3n profesional. SABER M\u00c1S\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/entornopruebas123.es\/en\/gimansio\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/entornopruebas123.es\/wp-content\/uploads\/2023\/10\/cropped-cropped-8e07e69f-9663-45ec-bb07-7f5997f2fe67.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/entornopruebas123.es\/wp-content\/uploads\/2023\/10\/cropped-cropped-8e07e69f-9663-45ec-bb07-7f5997f2fe67.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-10-03T10:48:01+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-02-14T13:13:10+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"GIMNASIO - fitgymaltea.es\" \/>\n\t\t<meta name=\"twitter:description\" content=\"FITGYM ALTEA GIMNASIO galer\u00eda NUESTRAS ACTIVIDADES VER M\u00c1S ENTRENA CON LAS MEJORES INSTALACIONES El gimnasio tiene varios equipos y \u00e1reas para hacer ejercicios, como musculaci\u00f3n, cardio, yoga, zumba y m\u00e1s. Tambi\u00e9n ofrece servicios como vestidores, ba\u00f1os, cafeter\u00edas y peque\u00f1a tienda de suplementos. Es perfecto para cualquier nivel deportivo y cuenta con supervisi\u00f3n profesional. SABER M\u00c1S\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/entornopruebas123.es\/wp-content\/uploads\/2023\/10\/cropped-cropped-8e07e69f-9663-45ec-bb07-7f5997f2fe67.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/entornopruebas123.es\\\/en\\\/gimansio\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/entornopruebas123.es\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/entornopruebas123.es\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/entornopruebas123.es\\\/en\\\/gimansio\\\/#listItem\",\"name\":\"GIMNASIO\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/entornopruebas123.es\\\/en\\\/gimansio\\\/#listItem\",\"position\":2,\"name\":\"GIMNASIO\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/entornopruebas123.es\\\/en#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/entornopruebas123.es\\\/en\\\/#organization\",\"name\":\"fitgymaltea.es\",\"url\":\"https:\\\/\\\/entornopruebas123.es\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/entornopruebas123.es\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/cropped-cropped-8e07e69f-9663-45ec-bb07-7f5997f2fe67.png\",\"@id\":\"https:\\\/\\\/entornopruebas123.es\\\/en\\\/gimansio\\\/#organizationLogo\",\"width\":200,\"height\":97},\"image\":{\"@id\":\"https:\\\/\\\/entornopruebas123.es\\\/en\\\/gimansio\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/entornopruebas123.es\\\/en\\\/gimansio\\\/#webpage\",\"url\":\"https:\\\/\\\/entornopruebas123.es\\\/en\\\/gimansio\\\/\",\"name\":\"GIMNASIO - fitgymaltea.es\",\"description\":\"FITGYM ALTEA GIMNASIO galer\\u00eda NUESTRAS ACTIVIDADES VER M\\u00c1S ENTRENA CON LAS MEJORES INSTALACIONES El gimnasio tiene varios equipos y \\u00e1reas para hacer ejercicios, como musculaci\\u00f3n, cardio, yoga, zumba y m\\u00e1s. Tambi\\u00e9n ofrece servicios como vestidores, ba\\u00f1os, cafeter\\u00edas y peque\\u00f1a tienda de suplementos. Es perfecto para cualquier nivel deportivo y cuenta con supervisi\\u00f3n profesional. SABER M\\u00c1S\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/entornopruebas123.es\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/entornopruebas123.es\\\/en\\\/gimansio\\\/#breadcrumblist\"},\"datePublished\":\"2023-10-03T12:48:01+02:00\",\"dateModified\":\"2024-02-14T14:13:10+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/entornopruebas123.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/entornopruebas123.es\\\/en\\\/\",\"name\":\"fitgymaltea.es\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/entornopruebas123.es\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"GIMNASIO - fitgymaltea.es","description":"FITGYM ALTEA GIMNASIO galer\u00eda NUESTRAS ACTIVIDADES VER M\u00c1S ENTRENA CON LAS MEJORES INSTALACIONES El gimnasio tiene varios equipos y \u00e1reas para hacer ejercicios, como musculaci\u00f3n, cardio, yoga, zumba y m\u00e1s. Tambi\u00e9n ofrece servicios como vestidores, ba\u00f1os, cafeter\u00edas y peque\u00f1a tienda de suplementos. Es perfecto para cualquier nivel deportivo y cuenta con supervisi\u00f3n profesional. SABER M\u00c1S","canonical_url":"https:\/\/entornopruebas123.es\/en\/gimansio\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/entornopruebas123.es\/en\/gimansio\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/entornopruebas123.es\/en#listItem","position":1,"name":"Home","item":"https:\/\/entornopruebas123.es\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/entornopruebas123.es\/en\/gimansio\/#listItem","name":"GIMNASIO"}},{"@type":"ListItem","@id":"https:\/\/entornopruebas123.es\/en\/gimansio\/#listItem","position":2,"name":"GIMNASIO","previousItem":{"@type":"ListItem","@id":"https:\/\/entornopruebas123.es\/en#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/entornopruebas123.es\/en\/#organization","name":"fitgymaltea.es","url":"https:\/\/entornopruebas123.es\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/entornopruebas123.es\/wp-content\/uploads\/2023\/10\/cropped-cropped-8e07e69f-9663-45ec-bb07-7f5997f2fe67.png","@id":"https:\/\/entornopruebas123.es\/en\/gimansio\/#organizationLogo","width":200,"height":97},"image":{"@id":"https:\/\/entornopruebas123.es\/en\/gimansio\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/entornopruebas123.es\/en\/gimansio\/#webpage","url":"https:\/\/entornopruebas123.es\/en\/gimansio\/","name":"GIMNASIO - fitgymaltea.es","description":"FITGYM ALTEA GIMNASIO galer\u00eda NUESTRAS ACTIVIDADES VER M\u00c1S ENTRENA CON LAS MEJORES INSTALACIONES El gimnasio tiene varios equipos y \u00e1reas para hacer ejercicios, como musculaci\u00f3n, cardio, yoga, zumba y m\u00e1s. Tambi\u00e9n ofrece servicios como vestidores, ba\u00f1os, cafeter\u00edas y peque\u00f1a tienda de suplementos. Es perfecto para cualquier nivel deportivo y cuenta con supervisi\u00f3n profesional. SABER M\u00c1S","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/entornopruebas123.es\/en\/#website"},"breadcrumb":{"@id":"https:\/\/entornopruebas123.es\/en\/gimansio\/#breadcrumblist"},"datePublished":"2023-10-03T12:48:01+02:00","dateModified":"2024-02-14T14:13:10+01:00"},{"@type":"WebSite","@id":"https:\/\/entornopruebas123.es\/en\/#website","url":"https:\/\/entornopruebas123.es\/en\/","name":"fitgymaltea.es","inLanguage":"en-GB","publisher":{"@id":"https:\/\/entornopruebas123.es\/en\/#organization"}}]},"og:locale":"en_GB","og:site_name":"fitgymaltea.es -","og:type":"article","og:title":"GIMNASIO - fitgymaltea.es","og:description":"FITGYM ALTEA GIMNASIO galer\u00eda NUESTRAS ACTIVIDADES VER M\u00c1S ENTRENA CON LAS MEJORES INSTALACIONES El gimnasio tiene varios equipos y \u00e1reas para hacer ejercicios, como musculaci\u00f3n, cardio, yoga, zumba y m\u00e1s. Tambi\u00e9n ofrece servicios como vestidores, ba\u00f1os, cafeter\u00edas y peque\u00f1a tienda de suplementos. Es perfecto para cualquier nivel deportivo y cuenta con supervisi\u00f3n profesional. SABER M\u00c1S","og:url":"https:\/\/entornopruebas123.es\/en\/gimansio\/","og:image":"https:\/\/entornopruebas123.es\/wp-content\/uploads\/2023\/10\/cropped-cropped-8e07e69f-9663-45ec-bb07-7f5997f2fe67.png","og:image:secure_url":"https:\/\/entornopruebas123.es\/wp-content\/uploads\/2023\/10\/cropped-cropped-8e07e69f-9663-45ec-bb07-7f5997f2fe67.png","article:published_time":"2023-10-03T10:48:01+00:00","article:modified_time":"2024-02-14T13:13:10+00:00","twitter:card":"summary_large_image","twitter:title":"GIMNASIO - fitgymaltea.es","twitter:description":"FITGYM ALTEA GIMNASIO galer\u00eda NUESTRAS ACTIVIDADES VER M\u00c1S ENTRENA CON LAS MEJORES INSTALACIONES El gimnasio tiene varios equipos y \u00e1reas para hacer ejercicios, como musculaci\u00f3n, cardio, yoga, zumba y m\u00e1s. Tambi\u00e9n ofrece servicios como vestidores, ba\u00f1os, cafeter\u00edas y peque\u00f1a tienda de suplementos. Es perfecto para cualquier nivel deportivo y cuenta con supervisi\u00f3n profesional. SABER M\u00c1S","twitter:image":"https:\/\/entornopruebas123.es\/wp-content\/uploads\/2023\/10\/cropped-cropped-8e07e69f-9663-45ec-bb07-7f5997f2fe67.png"},"aioseo_meta_data":{"post_id":"44","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-10-03 10:48:01","updated":"2025-06-04 15:48:29","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/entornopruebas123.es\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tGIMNASIO\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/entornopruebas123.es\/en"},{"label":"GIMNASIO","link":"https:\/\/entornopruebas123.es\/en\/gimansio\/"}],"_links":{"self":[{"href":"https:\/\/entornopruebas123.es\/en\/wp-json\/wp\/v2\/pages\/44"}],"collection":[{"href":"https:\/\/entornopruebas123.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/entornopruebas123.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/entornopruebas123.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entornopruebas123.es\/en\/wp-json\/wp\/v2\/comments?post=44"}],"version-history":[{"count":149,"href":"https:\/\/entornopruebas123.es\/en\/wp-json\/wp\/v2\/pages\/44\/revisions"}],"predecessor-version":[{"id":1671,"href":"https:\/\/entornopruebas123.es\/en\/wp-json\/wp\/v2\/pages\/44\/revisions\/1671"}],"wp:attachment":[{"href":"https:\/\/entornopruebas123.es\/en\/wp-json\/wp\/v2\/media?parent=44"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}